{"id":5820,"date":"2026-06-30T16:21:07","date_gmt":"2026-06-30T16:21:07","guid":{"rendered":"https:\/\/usatravelo.com\/?post_type=listing&#038;p=5820"},"modified":"2026-06-30T16:21:08","modified_gmt":"2026-06-30T16:21:08","slug":"festival-de-jazz-du-centre-ville-de-new-york-new-york-etats-unis","status":"publish","type":"listing","link":"https:\/\/usatravelo.com\/fr\/event\/downtown-nyc-jazzfest-new-york-city-united-states\/","title":{"rendered":"Festival de jazz du centre-ville de New York 2027 \u2013 New York, \u00c9tats-Unis"},"content":{"rendered":"<h3 class=\"wp-block-heading\">Vue d'ensemble<\/h3>\n\n\n\n<p id=\"p-rc_bf048710aa45d0c4-316\">Le Downtown NYC JazzFest est une vitrine spectaculaire du patrimoine sonore et de l&#039;exp\u00e9rimentation contemporaine, c\u00e9l\u00e9brant l&#039;h\u00e9ritage historique du jazz dans le Lower Manhattan.<sup><\/sup> Organis\u00e9 en \u00e9troite collaboration avec des lieux musicaux novateurs et des institutions h\u00f4teli\u00e8res locales, ce rassemblement printanier de plusieurs jours anime un r\u00e9seau soigneusement s\u00e9lectionn\u00e9 de salons musicaux intimistes, de clubs underground et de salles d&#039;\u00e9coute souterraines. Le festival se positionne comme un rendez-vous incontournable o\u00f9 la culture jazz classique du milieu du XXe si\u00e8cle se m\u00eale harmonieusement \u00e0 l&#039;\u00e9nergie audacieuse et avant-gardiste de la sc\u00e8ne ind\u00e9pendante new-yorkaise contemporaine.<\/p>\n\n\n\n<p>Le programme du festival propose une programmation soigneusement \u00e9labor\u00e9e, m\u00ealant avec brio des ma\u00eetres internationaux de renom et les jeunes talents les plus prometteurs, \u00e9tudiants et professeurs confondus. Le public pourra assister \u00e0 de nombreux concerts en soir\u00e9e, des duels instrumentaux intimistes et des hommages th\u00e9matiques originaux qui insufflent une nouvelle vie aux sous-genres embl\u00e9matiques du jazz. Des duels de saxophones endiabl\u00e9s aux ensembles de piano novateurs, en passant par des performances vocales \u00e9mouvantes et des big bands endiabl\u00e9s, la programmation multi-sc\u00e8nes met en lumi\u00e8re la v\u00e9ritable diversit\u00e9 et la vitalit\u00e9 cr\u00e9ative du genre.<\/p>\n\n\n\n<p id=\"p-rc_bf048710aa45d0c4-317\">Au-del\u00e0 des performances acoustiques et \u00e9lectriques imm\u00e9diates, le rassemblement offre un espace accueillant et communautaire qui rend hommage aux mouvements historiques des lofts et des clubs de SoHo et de TriBeCa.<sup><\/sup> Attendees can experience world-class instrumentation while relaxing in stylized listening rooms that offer fine seasonal dining and artisanal cocktails. It remains an invaluable annual anchor for dedicated jazz purists and casual neighborhood strollers alike, preserving downtown Manhattan&#8217;s position as a legendary, living laboratory of live musical innovation.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Faits marquants de l'\u00e9v\u00e9nement<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Spectacles sous chapiteau<\/strong>Des programmes de concerts exceptionnels en soir\u00e9e, mettant en vedette des compositeurs prim\u00e9s, des virtuoses l\u00e9gendaires de la batterie et des artistes de renomm\u00e9e internationale.<\/li>\n\n\n\n<li><strong>Duels instrumentaux<\/strong>Des batailles musicales th\u00e9matiques \u00e9nergiques et des solos enflamm\u00e9s de saxophones t\u00e9nor qui capturent l&#039;esprit de comp\u00e9tition classique de l&#039;histoire du jazz.<\/li>\n\n\n\n<li><strong>Vitrines de jeunes talents<\/strong>Des cr\u00e9neaux horaires d\u00e9di\u00e9s aux spectacles en journ\u00e9e offrent une plateforme de grande visibilit\u00e9 aux brillants ensembles \u00e9tudiants et aux dipl\u00f4m\u00e9s des instituts locaux.<\/li>\n\n\n\n<li><strong>Lieux souterrains \u00e0 l&#039;ambiance particuli\u00e8re<\/strong>Des concerts intimistes de musique live sont organis\u00e9s dans des sous-sols magnifiquement am\u00e9nag\u00e9s et des salons d&#039;h\u00f4tels de quartier historiques.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Pourquoi participer ?<\/h3>\n\n\n\n<p>Assister \u00e0 ce rassemblement musical en plein c\u0153ur de New York offre aux m\u00e9lomanes une occasion unique d&#039;appr\u00e9cier des performances de jazz exceptionnelles dans des cadres intimistes et \u00e0 l&#039;acoustique remarquable. La programmation soign\u00e9e rompt avec la froideur des grands stades, permettant aux spectateurs de se trouver \u00e0 quelques centim\u00e8tres seulement de percussionnistes, bassistes et instrumentistes \u00e0 vent de renom. En privil\u00e9giant les espaces o\u00f9 l&#039;improvisation et la virtuosit\u00e9 sont \u00e0 l&#039;honneur, le festival propose une immersion profond\u00e9ment personnelle et authentique dans la vie nocturne new-yorkaise.<\/p>\n\n\n\n<p id=\"p-rc_bf048710aa45d0c4-321\">Ce rassemblement est id\u00e9al pour les puristes du bebop traditionnel, les amateurs de fusion exp\u00e9rimentale, les cr\u00e9ateurs locaux, les passionn\u00e9s de voyages et les jeunes instrumentistes d\u00e9sireux d&#039;apprendre les techniques harmoniques en direct. Participer \u00e0 cet \u00e9v\u00e9nement offre \u00e9galement l&#039;avantage d&#039;une conception unique, alliant harmonieusement un niveau artistique international \u00e0 un accueil chaleureux et une restauration raffin\u00e9e.<sup><\/sup> Que vous souhaitiez d\u00e9couvrir votre prochain quatuor contemporain pr\u00e9f\u00e9r\u00e9, profiter d&#039;une soir\u00e9e raffin\u00e9e de musique en direct entre amis ou soutenir la pr\u00e9servation de la culture locale, ce festival vous offre un voyage printanier incomparable.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Date &amp; Duration<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Date de l'\u00e9v\u00e9nement<\/strong>Au cours du mois de juin 2027 (dates exactes \u00e0 d\u00e9terminer)<\/li>\n\n\n\n<li><strong>Dur\u00e9e de l'\u00e9v\u00e9nement<\/strong>Cinq soir\u00e9es cons\u00e9cutives de programmation musicale intensive et de sessions de pr\u00e9sentation cons\u00e9cutives<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading has-text-color has-link-color wp-elements-d86345e8a3bee47c09c2dafa036adeb2\" style=\"color:#194690\">Vous visitez cet \u00e9v\u00e9nement ? Ne manquez pas ces activit\u00e9s et exp\u00e9riences locales \u00e9tonnantes pendant votre s\u00e9jour.<\/h3>\n\n\n\n<div data-gyg-href=\"https:\/\/widget.getyourguide.com\/default\/activities.frame\" data-gyg-location-id=\"59\" data-gyg-locale-code=\"en-US\" data-gyg-widget=\"activities\" data-gyg-number-of-items=\"3\" data-gyg-partner-id=\"SVEESWP\"><span>Propuls\u00e9 par <a target=\"_blank\" rel=\"sponsored\" href=\"https:\/\/www.getyourguide.com\/new-york-city-l59\/\">GetYourGuide<\/a><\/span><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Information sur les billets<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Comment les billets sont-ils vendus ?<\/strong>Les billets d&#039;entr\u00e9e g\u00e9n\u00e9rale et les coupons individuels sont vendus en ligne via les plateformes de billetterie des principaux h\u00f4tels et clubs partenaires.<\/li>\n\n\n\n<li><strong>Type d'admission<\/strong>Les clients peuvent r\u00e9server des places sp\u00e9cifiques pour les spectacles principaux ou acc\u00e9der \u00e0 des espaces lounge d\u00e9contract\u00e9s d\u00e9sign\u00e9s l&#039;apr\u00e8s-midi sans r\u00e9servation pr\u00e9alable.<\/li>\n\n\n\n<li><strong>Prix des billets<\/strong>Les tarifs des spectacles individuels varient de 0 USD minimum pour des showcases sp\u00e9cifiques dans des bars l&#039;apr\u00e8s-midi du week-end jusqu&#039;\u00e0 40 USD maximum pour des sets en cave en fin de soir\u00e9e.<\/li>\n\n\n\n<li><strong>Si\u00e8ges sp\u00e9ciaux<\/strong>Les options d&#039;am\u00e9nagement g\u00e9n\u00e9ral du club comprennent des tables standard adjacentes \u00e0 la sc\u00e8ne principale, des espaces au comptoir du bar et des lignes de vue d\u00e9gag\u00e9es pour les personnes debout.<\/li>\n\n\n\n<li><strong>Options VIP<\/strong>Des formules prioritaires sp\u00e9ciales peuvent \u00eatre organis\u00e9es directement aupr\u00e8s des lieux d&#039;accueil, offrant aux contributeurs des tables r\u00e9serv\u00e9es au premier rang, des d\u00eeners gastronomiques \u00e0 plusieurs plats et des rencontres priv\u00e9es avec les artistes.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Lieu \/ Emplacement<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Ville et pays<\/strong>New York, \u00c9tats-Unis<\/li>\n\n\n\n<li><strong>Nom du lieu<\/strong>: Le Django et certains \u00e9tablissements Soho Grand<\/li>\n\n\n\n<li><strong>Adresse sur Google Maps<\/strong>2 Avenue of the Americas, New York, NY 10013<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Informations sur le contact<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Courriel<\/strong>info@winterjazzfest.com<\/li>\n\n\n\n<li><strong>Num\u00e9ro de t\u00e9l\u00e9phone<\/strong>: +1 212-519-6600<\/li>\n\n\n\n<li><strong>Site officiel<\/strong>https:\/\/www.downtownnycjazzfest.com\/<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Options d&#039;h\u00e9bergement<\/h3>\n\n\n\n<p>Les quartiers de SoHo, TriBeCa et Greenwich Village abritent une s\u00e9lection exceptionnelle d&#039;\u00e9tablissements de luxe au style industriel chic, d&#039;h\u00f4tels-boutiques design et de lofts cr\u00e9atifs. R\u00e9server une chambre directement dans l&#039;un des h\u00f4tels partenaires offre un confort optimal pendant le festival, permettant aux festivaliers de passer directement de la gastronomie raffin\u00e9e aux concerts en fin de soir\u00e9e, sans quitter l&#039;\u00e9tablissement.<\/p>\n\n\n\n<p>Pour les voyageurs en qu\u00eate d&#039;autres options d&#039;h\u00e9bergement, les quartiers voisins de Chinatown, du Lower East Side et du centre de Brooklyn offrent un large choix d&#039;h\u00f4tels d&#039;affaires et de suites modernes. Ces quartiers limitrophes sont tr\u00e8s bien desservis par plusieurs lignes de m\u00e9tro express, permettant de rejoindre les principaux sites du centre-ville en quelques minutes seulement.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Se rendre sur place<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>A\u00e9roport le plus proche<\/strong>L&#039;a\u00e9roport LaGuardia se situe \u00e0 environ 11 miles des principaux lieux de divertissement de SoHo, tandis que l&#039;a\u00e9roport international John F. Kennedy est \u00e0 environ 18 miles.<\/li>\n\n\n\n<li><strong>Station de train\/m\u00e9tro la plus proche<\/strong>La station de m\u00e9tro Canal Street et l&#039;arr\u00eat de m\u00e9tro Franklin Street offrent un acc\u00e8s imm\u00e9diat \u00e0 plusieurs lignes de train importantes, \u00e0 quelques p\u00e2t\u00e9s de maisons seulement des lieux de r\u00e9ception.<\/li>\n\n\n\n<li><strong>Lignes de bus<\/strong>Plusieurs lignes de bus locales circulent r\u00e9guli\u00e8rement le long de Broadway et de l&#039;Avenue des Am\u00e9riques, d\u00e9posant les passagers \u00e0 quelques pas des entr\u00e9es principales du salon.<\/li>\n\n\n\n<li><strong>Disponibilit\u00e9 du parking<\/strong>Le stationnement dans les rues du quartier historique de Lower Manhattan est tr\u00e8s restreint, mais de nombreux parkings priv\u00e9s \u00e0 plusieurs niveaux existent le long des rues adjacentes Greenwich Street et Hudson Street.<\/li>\n\n\n\n<li><strong>Itin\u00e9raire en voiture<\/strong>Les automobilistes arrivant de l&#039;ext\u00e9rieur de Manhattan peuvent emprunter le tunnel Holland pour sortir directement dans le sud de Manhattan, en direction du sud vers Canal Street et West Broadway.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Qu'est-ce que cet \u00e9v\u00e9nement ?<\/h3>\n\n\n\n<p id=\"p-rc_bf048710aa45d0c4-327\">Cet \u00e9v\u00e9nement est un festival de musique printanier annuel se d\u00e9roulant dans plusieurs lieux et un rassemblement communautaire d\u00e9di\u00e9 \u00e0 honorer la riche histoire et l&#039;\u00e9volution continue du jazz dans le Lower Manhattan.<sup><\/sup> Il r\u00e9unit des t\u00eates d&#039;affiche l\u00e9gendaires, des ensembles exp\u00e9rimentaux et des professeurs d&#039;universit\u00e9 locaux pour pr\u00e9senter des concerts acoustiques et \u00e9lectriques de haute qualit\u00e9.<\/p>\n\n\n\n<p>The five-night schedule combines intimate club showcases, competitive instrumental duels, and student workshops into a unified neighborhood celebration. It operates as both a crucial platform for independent creative voices and an elegant driver of downtown New York&#8217;s historic nightlife legacy.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pourquoi est-il populaire ?<\/h3>\n\n\n\n<p id=\"p-rc_bf048710aa45d0c4-328\">Cet \u00e9v\u00e9nement est immens\u00e9ment populaire car il ram\u00e8ne le jazz en direct dans son environnement le plus authentique et le plus historique : les caves souterraines \u00e0 l&#039;atmosph\u00e8re tamis\u00e9e et les salons intimes des quartiers du Lower Manhattan.<sup><\/sup> Elle s&#039;affranchit totalement de l&#039;atmosph\u00e8re formelle et st\u00e9rile des grandes salles de concert pour offrir un spectacle musical brut et sans filtre.<\/p>\n\n\n\n<p>De plus, la programmation brillante cr\u00e9e syst\u00e9matiquement des moments palpitants et uniques, comme les duels sc\u00e9niques spontan\u00e9s et les improvisations endiabl\u00e9es r\u00e9unissant des l\u00e9gendes du jazz. L&#039;alliance parfaite d&#039;instruments de renomm\u00e9e mondiale et d&#039;une offre gastronomique raffin\u00e9e en fait un rendez-vous annuel incontournable pour la sc\u00e8ne artistique locale.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Conseils avant de partir<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>R\u00e9servez votre table<\/strong>R\u00e9servez vos places en ligne bien \u00e0 l&#039;avance, car la capacit\u00e9 de ces caves souterraines intimistes est tr\u00e8s limit\u00e9e et les places partent vite.<\/li>\n\n\n\n<li><strong>V\u00e9rifiez les horaires fixes<\/strong>Consultez le programme d\u00e9taill\u00e9 des artistes chaque soir sur votre t\u00e9l\u00e9phone pour organiser vos d\u00e9placements entre les concerts acoustiques en d\u00e9but de soir\u00e9e et les spectacles des grands orchestres \u00e0 minuit.<\/li>\n\n\n\n<li><strong>Tenue d\u00e9contract\u00e9e \u00e9l\u00e9gante<\/strong>Portez une tenue sophistiqu\u00e9e et d\u00e9contract\u00e9e qui s&#039;int\u00e8gre naturellement dans l&#039;ambiance \u00e9l\u00e9gante d&#039;un salon d&#039;h\u00f4tel haut de gamme de Manhattan ou dans l&#039;atmosph\u00e8re raffin\u00e9e d&#039;une cave \u00e0 vin en sous-sol.<\/li>\n\n\n\n<li><strong>Arrivez pour le d\u00eener<\/strong>Arrivez au moins quarante-cinq minutes avant le d\u00e9but du concert si vous souhaitez profiter de la carte compl\u00e8te de cocktails et des options de d\u00eener gastronomique avant que la musique ne commence.<\/li>\n\n\n\n<li><strong>Parlez \u00e0 voix basse<\/strong>Respectez l&#039;acoustique intimiste des salles de spectacle en limitant les conversations \u00e0 voix basse pendant que les musiciens sont sur sc\u00e8ne.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Exp\u00e9riences des participants<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Assister \u00e0 un duel de saxophones de niveau mondial depuis une table au premier rang dans cette magnifique cave souterraine a \u00e9t\u00e9 un moment fort de mon ann\u00e9e.<\/li>\n\n\n\n<li>J&#039;ai ador\u00e9 l&#039;ambiance sophistiqu\u00e9e et intime des lieux, et les cocktails \u00e9taient tout aussi incroyables que les instruments jou\u00e9s en direct sur sc\u00e8ne.<\/li>\n\n\n\n<li>Le festival r\u00e9ussit \u00e0 merveille \u00e0 mettre en valeur de jeunes talents prometteurs aux c\u00f4t\u00e9s de ma\u00eetres confirm\u00e9s qui jouent dans la ville depuis des d\u00e9cennies.<\/li>\n<\/ul>","protected":false},"author":2,"featured_media":5822,"comment_status":"open","ping_status":"closed","template":"","meta":[],"listing_category":[],"event_category":[72],"service_category":[],"rental_category":[],"classifieds_category":[],"listing_feature":[],"region":[34],"city":[84],"class_list":["post-5820","listing","type-listing","status-publish","has-post-thumbnail","hentry","event_category-music","region-northeast","city-new-york"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Downtown NYC JazzFest 2027 \u2013 New York City, United States - USA Travelo<\/title>\n<meta name=\"description\" content=\"Downtown NYC JazzFest 2027 in New York City, United States is an exciting annual jazz festival featuring acclaimed musicians, emerging artists, and live performances across iconic downtown venues, celebrating the vibrant spirit and diversity of New York City&#039;s jazz scene.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/usatravelo.com\/fr\/evenement\/festival-de-jazz-du-centre-ville-de-new-york-new-york-etats-unis\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Downtown NYC JazzFest 2027 \u2013 New York City, United States - USA Travelo\" \/>\n<meta property=\"og:description\" content=\"Downtown NYC JazzFest 2027 in New York City, United States is an exciting annual jazz festival featuring acclaimed musicians, emerging artists, and live performances across iconic downtown venues, celebrating the vibrant spirit and diversity of New York City&#039;s jazz scene.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/usatravelo.com\/fr\/evenement\/festival-de-jazz-du-centre-ville-de-new-york-new-york-etats-unis\/\" \/>\n<meta property=\"og:site_name\" content=\"USA Travelo\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-30T16:21:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/usatravelo.com\/wp-content\/uploads\/2026\/06\/Jumanne-Smith-Square-Django-900x900-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/usatravelo.com\\\/event\\\/downtown-nyc-jazzfest-new-york-city-united-states\\\/\",\"url\":\"https:\\\/\\\/usatravelo.com\\\/event\\\/downtown-nyc-jazzfest-new-york-city-united-states\\\/\",\"name\":\"Downtown NYC JazzFest 2027 \u2013 New York City, United States - USA Travelo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/usatravelo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/usatravelo.com\\\/event\\\/downtown-nyc-jazzfest-new-york-city-united-states\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/usatravelo.com\\\/event\\\/downtown-nyc-jazzfest-new-york-city-united-states\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/usatravelo.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Jumanne-Smith-Square-Django-900x900-1.webp\",\"datePublished\":\"2026-06-30T16:21:07+00:00\",\"dateModified\":\"2026-06-30T16:21:08+00:00\",\"description\":\"Downtown NYC JazzFest 2027 in New York City, United States is an exciting annual jazz festival featuring acclaimed musicians, emerging artists, and live performances across iconic downtown venues, celebrating the vibrant spirit and diversity of New York City's jazz scene.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/usatravelo.com\\\/event\\\/downtown-nyc-jazzfest-new-york-city-united-states\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/usatravelo.com\\\/event\\\/downtown-nyc-jazzfest-new-york-city-united-states\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/usatravelo.com\\\/event\\\/downtown-nyc-jazzfest-new-york-city-united-states\\\/#primaryimage\",\"url\":\"https:\\\/\\\/usatravelo.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Jumanne-Smith-Square-Django-900x900-1.webp\",\"contentUrl\":\"https:\\\/\\\/usatravelo.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Jumanne-Smith-Square-Django-900x900-1.webp\",\"width\":900,\"height\":900,\"caption\":\"Downtown NYC JazzFest\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/usatravelo.com\\\/event\\\/downtown-nyc-jazzfest-new-york-city-united-states\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/usatravelo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\\\/\\\/usatravelo.com\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Downtown NYC JazzFest 2027 \u2013 New York City, United States\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/usatravelo.com\\\/#website\",\"url\":\"https:\\\/\\\/usatravelo.com\\\/\",\"name\":\"USA Travelo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/usatravelo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/usatravelo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/usatravelo.com\\\/#organization\",\"name\":\"USA Travelo\",\"url\":\"https:\\\/\\\/usatravelo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/usatravelo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/usatravelo.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/USA-Travelo-11.png\",\"contentUrl\":\"https:\\\/\\\/usatravelo.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/USA-Travelo-11.png\",\"width\":1600,\"height\":400,\"caption\":\"USA Travelo\"},\"image\":{\"@id\":\"https:\\\/\\\/usatravelo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Festival de jazz du centre-ville de New York 2027 \u2013 New York, \u00c9tats-Unis - USA Travelo","description":"Le Downtown NYC JazzFest 2027, qui se d\u00e9roule \u00e0 New York, aux \u00c9tats-Unis, est un festival de jazz annuel passionnant mettant en vedette des musiciens de renom, des artistes \u00e9mergents et des performances en direct dans des lieux embl\u00e9matiques du centre-ville, c\u00e9l\u00e9brant l&#039;esprit vibrant et la diversit\u00e9 de la sc\u00e8ne jazz new-yorkaise.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/usatravelo.com\/fr\/evenement\/festival-de-jazz-du-centre-ville-de-new-york-new-york-etats-unis\/","og_locale":"fr_FR","og_type":"article","og_title":"Downtown NYC JazzFest 2027 \u2013 New York City, United States - USA Travelo","og_description":"Downtown NYC JazzFest 2027 in New York City, United States is an exciting annual jazz festival featuring acclaimed musicians, emerging artists, and live performances across iconic downtown venues, celebrating the vibrant spirit and diversity of New York City's jazz scene.","og_url":"https:\/\/usatravelo.com\/fr\/evenement\/festival-de-jazz-du-centre-ville-de-new-york-new-york-etats-unis\/","og_site_name":"USA Travelo","article_modified_time":"2026-06-30T16:21:08+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/usatravelo.com\/wp-content\/uploads\/2026\/06\/Jumanne-Smith-Square-Django-900x900-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/usatravelo.com\/event\/downtown-nyc-jazzfest-new-york-city-united-states\/","url":"https:\/\/usatravelo.com\/event\/downtown-nyc-jazzfest-new-york-city-united-states\/","name":"Festival de jazz du centre-ville de New York 2027 \u2013 New York, \u00c9tats-Unis - USA Travelo","isPartOf":{"@id":"https:\/\/usatravelo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/usatravelo.com\/event\/downtown-nyc-jazzfest-new-york-city-united-states\/#primaryimage"},"image":{"@id":"https:\/\/usatravelo.com\/event\/downtown-nyc-jazzfest-new-york-city-united-states\/#primaryimage"},"thumbnailUrl":"https:\/\/usatravelo.com\/wp-content\/uploads\/2026\/06\/Jumanne-Smith-Square-Django-900x900-1.webp","datePublished":"2026-06-30T16:21:07+00:00","dateModified":"2026-06-30T16:21:08+00:00","description":"Le Downtown NYC JazzFest 2027, qui se d\u00e9roule \u00e0 New York, aux \u00c9tats-Unis, est un festival de jazz annuel passionnant mettant en vedette des musiciens de renom, des artistes \u00e9mergents et des performances en direct dans des lieux embl\u00e9matiques du centre-ville, c\u00e9l\u00e9brant l&#039;esprit vibrant et la diversit\u00e9 de la sc\u00e8ne jazz new-yorkaise.","breadcrumb":{"@id":"https:\/\/usatravelo.com\/event\/downtown-nyc-jazzfest-new-york-city-united-states\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/usatravelo.com\/event\/downtown-nyc-jazzfest-new-york-city-united-states\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/usatravelo.com\/event\/downtown-nyc-jazzfest-new-york-city-united-states\/#primaryimage","url":"https:\/\/usatravelo.com\/wp-content\/uploads\/2026\/06\/Jumanne-Smith-Square-Django-900x900-1.webp","contentUrl":"https:\/\/usatravelo.com\/wp-content\/uploads\/2026\/06\/Jumanne-Smith-Square-Django-900x900-1.webp","width":900,"height":900,"caption":"Downtown NYC JazzFest"},{"@type":"BreadcrumbList","@id":"https:\/\/usatravelo.com\/event\/downtown-nyc-jazzfest-new-york-city-united-states\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/usatravelo.com\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/usatravelo.com\/events\/"},{"@type":"ListItem","position":3,"name":"Downtown NYC JazzFest 2027 \u2013 New York City, United States"}]},{"@type":"WebSite","@id":"https:\/\/usatravelo.com\/#website","url":"https:\/\/usatravelo.com\/","name":"USA Travelo","description":"","publisher":{"@id":"https:\/\/usatravelo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/usatravelo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/usatravelo.com\/#organization","name":"USA Travelo","url":"https:\/\/usatravelo.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/usatravelo.com\/#\/schema\/logo\/image\/","url":"https:\/\/usatravelo.com\/wp-content\/uploads\/2026\/04\/USA-Travelo-11.png","contentUrl":"https:\/\/usatravelo.com\/wp-content\/uploads\/2026\/04\/USA-Travelo-11.png","width":1600,"height":400,"caption":"USA Travelo"},"image":{"@id":"https:\/\/usatravelo.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/usatravelo.com\/fr\/wp-json\/wp\/v2\/listing\/5820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/usatravelo.com\/fr\/wp-json\/wp\/v2\/listing"}],"about":[{"href":"https:\/\/usatravelo.com\/fr\/wp-json\/wp\/v2\/types\/listing"}],"author":[{"embeddable":true,"href":"https:\/\/usatravelo.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/usatravelo.com\/fr\/wp-json\/wp\/v2\/comments?post=5820"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/usatravelo.com\/fr\/wp-json\/wp\/v2\/media\/5822"}],"wp:attachment":[{"href":"https:\/\/usatravelo.com\/fr\/wp-json\/wp\/v2\/media?parent=5820"}],"wp:term":[{"taxonomy":"listing_category","embeddable":true,"href":"https:\/\/usatravelo.com\/fr\/wp-json\/wp\/v2\/listing_category?post=5820"},{"taxonomy":"event_category","embeddable":true,"href":"https:\/\/usatravelo.com\/fr\/wp-json\/wp\/v2\/event_category?post=5820"},{"taxonomy":"service_category","embeddable":true,"href":"https:\/\/usatravelo.com\/fr\/wp-json\/wp\/v2\/service_category?post=5820"},{"taxonomy":"rental_category","embeddable":true,"href":"https:\/\/usatravelo.com\/fr\/wp-json\/wp\/v2\/rental_category?post=5820"},{"taxonomy":"classifieds_category","embeddable":true,"href":"https:\/\/usatravelo.com\/fr\/wp-json\/wp\/v2\/classifieds_category?post=5820"},{"taxonomy":"listing_feature","embeddable":true,"href":"https:\/\/usatravelo.com\/fr\/wp-json\/wp\/v2\/listing_feature?post=5820"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/usatravelo.com\/fr\/wp-json\/wp\/v2\/region?post=5820"},{"taxonomy":"city","embeddable":true,"href":"https:\/\/usatravelo.com\/fr\/wp-json\/wp\/v2\/city?post=5820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}